{"id":10283,"date":"2021-03-02T14:04:17","date_gmt":"2021-03-02T14:04:17","guid":{"rendered":"http:\/\/rivadaviamendoza.gob.ar\/hcd\/?p=10283"},"modified":"2023-08-08T15:38:31","modified_gmt":"2023-08-08T15:38:31","slug":"ordenanza-1234-2020-copy-copy-6-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-2-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-co-101","status":"publish","type":"post","link":"https:\/\/coworkdigital.com.ar\/hcd\/ordenanza-1234-2020-copy-copy-6-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-2-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-copy-co-101\/","title":{"rendered":"ORDEN DEL D\u00cdA N\u00ba 01-21"},"content":{"rendered":"<p><strong>A los<\/strong><\/p>\n<p><strong>Se\u00f1ores\/as Concejales<\/strong><\/p>\n<p><strong><u>PRESENTE<\/u><\/strong><\/p>\n<p>De mi mayor consideraci\u00f3n:<\/p>\n<p>Tengo el agrado de dirigirme a ustedes a fin de elevarle el Orden del D\u00eda N\u00ba 01\/21 para la Sesi\u00f3n Ordinaria del d\u00eda 02 de marzo de 2021, a la hora 09:00.<\/p>\n<p><strong><u>COMUNICACIONES OFICIALES<\/u><\/strong><\/p>\n<p>Expte. N\u00ba 2020-00302-2\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Presidente H.C.D. Rivadavia Prof. Mauricio Di C\u00e9sare, Informa expedientes para ser tratados en Periodo de Sesiones Ordinarias 2021.<\/p>\n<p>Expte. N\u00ba 2020-00313-9\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 H.C.D General Alvear \u2013 Mza. Remite Resoluci\u00f3n N\u00ba 5058-20. (L.P.P.)<\/p>\n<p>Expte. N\u00ba 2020-00314-7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 H.C.D. General Alvear \u2013 Mza. Remite Resoluci\u00f3n N\u00ba 5085-20. (L.P.P.)<\/p>\n<p>Expte. N\u00ba 2020-00315-4\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Lic. Adri\u00e1n M\u00e9ndez, Director a\/c Re.P.Ar \u2013 Re-Pr.I.V. (L.P.P.)<\/p>\n<p>Expte. N\u00ba 2021-00003-5\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Departamento Ejecutivo, Eleva Informe, Proyecto Ordenanza: Entidades Deportivas. (A.S.)<\/p>\n<p><strong><u>PETICIONES PARTICULARES<\/u><\/strong><\/p>\n<p>Expte. N\u00ba 2020-00310-5\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Luisina Coria, Gestora cultural, Solicita reuni\u00f3n con el Cuerpo Deliberativo. (A.S.)<\/p>\n<p>Expte. N\u00ba 2020-00317-0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Concejal Francisco Novello Informa extrav\u00edo de tel\u00e9fono celular. (Sec.)<\/p>\n<p>Expte. N\u00ba 2021-00001-9\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Encargada del Asilo de Ancianos, San Isidro Labrador, solicita: Colaboraci\u00f3n pa\u00f1ales. (Sec.)<\/p>\n<p>Expte. N\u00ba 2021-00005-0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Presidente Cooperadora Hospital Saporiti, se\u00f1ora Silvia Baigorria de Mansur, solicita colaboraci\u00f3n. (Sec.)<\/p>\n<p>Expte. N\u00ba 2021-00012-6\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Vecinos de calle Villar, solicitan la Banca del Pueblo. (L.P.P.)<\/p>\n<p>Expte. N\u00ba 2021-00013-4\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Escuela N\u00ba 1-370 \u201cMaestro Acevedo\u201d, solicita: Donaci\u00f3n de Banderas Nacional y Provincial. (A.S.)<\/p>\n<p>Expte. N\u00ba 2021-00027-4\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Juan Carlos Leal, presenta nota. (O.P.)<\/p>\n<p><strong><u>PROYECTOS PRESENTADOS<\/u><\/strong><\/p>\n<p>Expte. N\u00ba 2021-00020-9\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Bloque U.C.R. Concejales Abate-Rodr\u00edguez presentan: Proyecto de\u00a0 Declaraci\u00f3n: Declarar patrimonio del Departamento un Aguaribay. (M.A.)<\/p>\n<p>Expte. N\u00ba 2021-00021-7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Bloque U.C.R. Concejales Abate-Rodr\u00edguez presentan: Proyecto de\u00a0 Resoluci\u00f3n: Adhesi\u00f3n a la Ley Yolanda. (L.P.P.)<\/p>\n<p>Expte. N\u00ba 2021-00022-5\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Bloque U.C.R. Concejales Abate-Rodr\u00edguez presentan: Proyecto de\u00a0 Ordenanza: Mujeres Destacadas Rivadavienses. (L.P.P.)<\/p>\n<p>Expte. N\u00ba 2021-00023-3\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Bloque U.C.R. Concejales Abate-Rodr\u00edguez presentan: Proyecto de\u00a0 Declaraci\u00f3n: Declarar de Inter\u00e9s Departamental el programa \u201cBotellas de Amor\u201d. (M.A.)<\/p>\n<p>Expte. N\u00ba 2021-00024-1\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Bloque U.C.R. Concejales Abate-Rodr\u00edguez presentan: Proyecto de\u00a0 Resoluci\u00f3n: Galer\u00eda hist\u00f3rica de Intendentes y Presidentes del H.C.D. desde el retorno de la democracia hasta la fecha. (L.P.P.)<\/p>\n<p>Expte. N\u00ba 2021-00025-8\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Bloque U.C.R. Concejales Machin-Amar presentan: Proyecto de\u00a0 Ordenanza: Agr\u00e9guese el punto a al art. 1\u00ba de la Ordenanza N\u00ba 5013\/2020. (L.P.P.)<\/p>\n<p>Expte. N\u00ba 2021-00026-6\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Bloque U.C.R. Concejales Machin-Amar presentan: Proyecto de\u00a0 Resoluci\u00f3n: Luminarias calle San Expedito distrito La Central. (O.P.)<\/p>\n<p>Expte. N\u00ba 2021-00028-2\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Bloques J.D.Per\u00f3n e Intransigente Concejales Novello-Santarelli presentan: Pedido de Informe: Situaci\u00f3n de empleados municipales. (L.P.P.)<\/p>\n<p>Expte. N\u00ba 2021-00029-0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Bloque U.C.R. Concejales Amar- Machin presentan: Proyecto de Resoluci\u00f3n: Instalaci\u00f3n en las ciclov\u00edas de bebederos p\u00fablicos de agua potable y puntos verdes para clasificar residuos secos. (O.P.)<\/p>\n<p>Expte. N\u00ba 2021-00030-8\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Bloques J.D.Per\u00f3n e Intransigente Concejales Novello-Santarelli presentan: Proyecto de Ordenanza: Presupuesto p\u00fablico elaborado a trav\u00e9s de la participaci\u00f3n ciudadana. (L.P.P.)<\/p>\n<p><strong><u>ASUNTOS CON DESPACHO<\/u><\/strong><\/p>\n<p>Expte. N\u00ba 2020-00308-9\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Expte. Municipal N\u00ba 2020-15125-0 Municipalidad de Rivadavia, Remite Copia Balance Ingresos y Egresos, Septiembre 2020.<\/p>\n<p>Expte. N\u00ba 2021-00015-9\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Expte. Municipal N\u00ba 2020-15166-4 Cooperativa Flor de Retamo Limitada, Solicita donaci\u00f3n de calles.<\/p>\n<p>Expte. N\u00ba 2021-00016-7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Expte. Municipal N\u00ba 2020-15334-8 Municipalidad de Rivadavia, Presentaci\u00f3n informe requeridos por la Ley de Responsabilidad Fiscal, correspondiente 3\u00ba trimestre.<\/p>\n<p>Expte. N\u00ba 2021-00018-3\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Expte. Municipal N\u00ba 2020-16839-5 Municipalidad de Rivadavia, Remite Copia Balance Ingresos y Egresos, Octubre 2020.<\/p>\n<p>Expte. N\u00ba 2021-00019-1\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Expte. Municipal N\u00ba 2021-01280-8 Municipalidad de Rivadavia, Remite Copia Balance Ingresos y Egresos, Noviembre 2020.<\/p>\n<p><strong><u>ARCHIVO<\/u><\/strong><\/p>\n<p>Expte. N\u00ba 2020-00311-3\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Municipalidad de Rivadavia, Invita Actos Licitatorios.<\/p>\n<p>Expte. N\u00ba 2020-00316-2\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0 Concejal Bloque U.C.R. Fernando Rodr\u00edguez, informa que se \u00a0\u00a0\u00a0ausentar\u00e1 por motivos personales.<\/p>\n<p>Expte. N\u00ba 2020-00318-8\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Concejal Mar\u00eda Jos\u00e9 Gil, Informa que se ausentar\u00e1 de la provincia desde el 08 al 18 de enero del 2021.<\/p>\n<p>Expte. N\u00ba 2021-00002-7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0 Concejal Bloque U.C.R. Anabella Machin, Informa que seausentar\u00e1 por motivos personales.<\/p>\n<p>Expte. N\u00ba 2021-00004-3\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0 Secretario Bloque U.C.R. Mariano Amprino, Informa que se ausentar\u00e1 de la provincia desde el 18\/01 al 29\/01.<\/p>\n<p>Expte. N\u00ba 2021-00006-8\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0 Secretaria Bloque U.C.R. Pamela Nacer, Informa que se ausentar\u00e1 por motivos personales.<\/p>\n<p>Expte. N\u00ba 2021-00007-6\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0 Municipalidad de Rivadavia, Direcci\u00f3n de Compras y Suministros, Invita Licitaci\u00f3n P\u00fablica d\u00eda 27 de enero de 2021.<\/p>\n<p>Expte. N\u00ba 2021-00008-4\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0 Municipalidad de Rivadavia, Direcci\u00f3n de Compras y Suministros, Invita Licitaci\u00f3n P\u00fablica mes de febrero 2021.<\/p>\n<p>Expte. N\u00ba 2021-00011-8\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0 Municipalidad de Rivadavia, Direcci\u00f3n de Compras y Suministros,\u00a0 Invita Licitaci\u00f3n P\u00fablica 22 y 24 de febrero 2021.<\/p>\n<p><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 MAR\u00cdA IN\u00c9S DALLAGO\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 MAURICIO DI C\u00c9SARE<\/strong><\/p>\n<p><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0SECRETARIA H.C.D.\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0PRESIDENTE\u00a0 H. C. D<\/strong><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/strong><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/strong><\/p>\n<p><a href=\"https:\/\/coworkdigital.com.ar\/hcd\/wp-content\/uploads\/2021\/11\/01-21.pdf\"><img decoding=\"async\" class=\"wp-image-6224 alignleft\" src=\"https:\/\/coworkdigital.com.ar\/hcd\/wp-content\/uploads\/2020\/06\/descarga_pdf-150x150.png\" width=\"50\" height=\"53\" srcset=\"https:\/\/coworkdigital.com.ar\/hcd\/wp-content\/uploads\/2020\/06\/descarga_pdf-282x300.png 282w, https:\/\/coworkdigital.com.ar\/hcd\/wp-content\/uploads\/2020\/06\/descarga_pdf.png 496w\" sizes=\"(max-width: 50px) 100vw, 50px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A los Se\u00f1ores\/as Concejales PRESENTE De mi mayor consideraci\u00f3n: Tengo el agrado de dirigirme a ustedes a fin de elevarle el Orden del D\u00eda N\u00ba 01\/21 para la Sesi\u00f3n Ordinaria del d\u00eda 02 de marzo de 2021, a la hora 09:00. COMUNICACIONES OFICIALES Expte. N\u00ba 2020-00302-2\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Presidente H.C.D. Rivadavia Prof. Mauricio Di C\u00e9sare, Informa expedientes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[73],"tags":[],"class_list":["post-10283","post","type-post","status-publish","format-standard","hentry","category-orden-del-dia"],"acf":[],"_links":{"self":[{"href":"https:\/\/coworkdigital.com.ar\/hcd\/wp-json\/wp\/v2\/posts\/10283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coworkdigital.com.ar\/hcd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coworkdigital.com.ar\/hcd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coworkdigital.com.ar\/hcd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coworkdigital.com.ar\/hcd\/wp-json\/wp\/v2\/comments?post=10283"}],"version-history":[{"count":1,"href":"https:\/\/coworkdigital.com.ar\/hcd\/wp-json\/wp\/v2\/posts\/10283\/revisions"}],"predecessor-version":[{"id":13187,"href":"https:\/\/coworkdigital.com.ar\/hcd\/wp-json\/wp\/v2\/posts\/10283\/revisions\/13187"}],"wp:attachment":[{"href":"https:\/\/coworkdigital.com.ar\/hcd\/wp-json\/wp\/v2\/media?parent=10283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coworkdigital.com.ar\/hcd\/wp-json\/wp\/v2\/categories?post=10283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coworkdigital.com.ar\/hcd\/wp-json\/wp\/v2\/tags?post=10283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}